{"id":1310,"date":"2026-05-12T16:30:00","date_gmt":"2026-05-12T19:30:00","guid":{"rendered":"https:\/\/betsson.sport\/br\/?p=1310"},"modified":"2026-05-12T10:47:11","modified_gmt":"2026-05-12T13:47:11","slug":"selecao-brasileira-thiago-silva-deixa-recado-ancelotti-antes-convocacao-final-copa","status":"publish","type":"post","link":"https:\/\/betsson.sport\/br\/noticias\/futebol\/mundial\/selecao-brasileira-thiago-silva-deixa-recado-ancelotti-antes-convocacao-final-copa\/","title":{"rendered":"Thiago Silva deixa recado a Ancelotti antes de convoca\u00e7\u00e3o final da Sele\u00e7\u00e3o Brasileira"},"content":{"rendered":"\n<p>O treinador da <strong>Sele\u00e7\u00e3o Brasileira<\/strong>, <strong>Carlo Ancelotti<\/strong>, enviou \u00e0 FIFA nesta segunda-feira (11) uma pr\u00e9-lista com <strong>55<\/strong> nomes cotados para disputar a <strong>Copa do Mundo<\/strong> de 2026. Entre os jogadores mencionados, est\u00e1 o experiente zagueiro <strong>Thiago Silva<\/strong>, que pode voltar a vestir a camisa do Brasil em mais um Mundial.<\/p>\n\n\n\n<p>Revelado pelo <strong>Fluminense<\/strong>, \u00eddolo na Europa, e dono de uma longa trajet\u00f3ria pela Canarinha, Thiago Silva est\u00e1 atualmente no <strong>Porto<\/strong>. Mesmo convivendo com alguns problemas f\u00edsicos ao longo da temporada, o defensor teve participa\u00e7\u00e3o importante na conquista antecipada do <strong>Campeonato Portugu\u00eas<\/strong>, reafirmando sua lideran\u00e7a e capacidade t\u00e9cnica dentro de campo.<\/p>\n\n\n\n<p>A poss\u00edvel volta do zagueiro \u00e0 sele\u00e7\u00e3o ganhou for\u00e7a principalmente ap\u00f3s a les\u00e3o de <strong>\u00c9der Milit\u00e3o<\/strong>, <a href=\"https:\/\/betsson.sport\/br\/noticias\/futebol\/mundial\/militao-passa-cirurgia-esta-fora-copa-do-mundo\/\"><strong>que ficar\u00e1 fora da Copa<\/strong><\/a>. Aos 41 anos, Thiago Silva divide opini\u00f5es entre os torcedores: enquanto alguns questionam sua idade e condi\u00e7\u00e3o f\u00edsica para disputar uma competi\u00e7\u00e3o de alto n\u00edvel, outros destacam sua experi\u00eancia, personalidade e hist\u00f3rico vitorioso como fatores que podem ser decisivos para o grupo brasileiro.<\/p>\n\n\n\n<p>Nas redes sociais, a possibilidade de convoca\u00e7\u00e3o do defensor movimentou debates acalorados. Muitos enxergam no jogador uma refer\u00eancia importante para um elenco que deve mesclar juventude e experi\u00eancia durante o torneio.<\/p>\n\n\n\n<p>Em entrevista \u00e0 <em>TNT Sports<\/em>, Thiago afirmou estar preparado para um eventual retorno.\u00a0\u201cEstou super dispon\u00edvel. Acho que o mister (Ancelotti) me conhece o suficiente para saber da minha disponibilidade\u201d, declarou o zagueiro.<\/p>\n\n\n\n<p>Apesar de demonstrar entusiasmo com a chance de disputar mais uma Copa do Mundo, o defensor tamb\u00e9m adotou um tom sereno ao comentar a possibilidade de ficar fora da lista final. \"Minha carreira foi linda. Se tiver que ir para mais uma Copa, estaremos juntos. Se n\u00e3o acontecer, s\u00f3 tenho a agradecer por tudo o que vivi e pelos momentos incr\u00edveis\u201d, afirmou.<\/p>\n\n\n\n<p>Agora, a expectativa gira em torno da convoca\u00e7\u00e3o oficial e da confirma\u00e7\u00e3o de Thiago Silva entre os nomes que representar\u00e3o o Brasil no Mundial de 2026.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s a divulga\u00e7\u00e3o da pr\u00e9-lista de convocados, zagueiro afirma estar preparado para voltar \u00e0 Sele\u00e7\u00e3o, mas diz encarar com tranquilidade uma poss\u00edvel aus\u00eancia na lista final.<\/p>\n","protected":false},"author":12,"featured_media":1311,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":true,"footnotes":""},"categories":[23],"tags":[],"country":[],"label":[],"class_list":["post-1310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundial"],"acf":[],"_links":{"self":[{"href":"https:\/\/betsson.sport\/br\/wp-json\/wp\/v2\/posts\/1310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/betsson.sport\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/betsson.sport\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/betsson.sport\/br\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/betsson.sport\/br\/wp-json\/wp\/v2\/comments?post=1310"}],"version-history":[{"count":0,"href":"https:\/\/betsson.sport\/br\/wp-json\/wp\/v2\/posts\/1310\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/betsson.sport\/br\/wp-json\/wp\/v2\/media\/1311"}],"wp:attachment":[{"href":"https:\/\/betsson.sport\/br\/wp-json\/wp\/v2\/media?parent=1310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/betsson.sport\/br\/wp-json\/wp\/v2\/categories?post=1310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/betsson.sport\/br\/wp-json\/wp\/v2\/tags?post=1310"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/betsson.sport\/br\/wp-json\/wp\/v2\/country?post=1310"},{"taxonomy":"label","embeddable":true,"href":"https:\/\/betsson.sport\/br\/wp-json\/wp\/v2\/label?post=1310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}