{"id":10931,"date":"2026-05-12T18:20:48","date_gmt":"2026-05-12T21:20:48","guid":{"rendered":"https:\/\/betsson.sport\/es\/?p=10931"},"modified":"2026-05-12T18:24:34","modified_gmt":"2026-05-12T21:24:34","slug":"chile-ya-eligio-su-seleccion-para-el-mundial-2026-portugal-lidera-la-encuesta","status":"publish","type":"post","link":"https:\/\/betsson.sport\/es\/noticias\/futbol\/mundial\/chile-ya-eligio-su-seleccion-para-el-mundial-2026-portugal-lidera-la-encuesta\/","title":{"rendered":"Chile ya eligi\u00f3 su selecci\u00f3n para el Mundial 2026: Portugal lidera la encuesta"},"content":{"rendered":"\n<p>Una encuesta realizada por Betsson entre marzo y abril de 2026 revela qu\u00e9 selecciones apoyan los chilenos en el Mundial 2026 ante la ausencia de la Roja, qu\u00e9 futbolistas despiertan mayor inter\u00e9s y cu\u00e1les son los equipos que generan m\u00e1s dudas de cara al torneo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"606\" height=\"1024\" src=\"https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/05\/Infographic_V2.jpg-606x1024.jpeg\" alt=\"\" class=\"wp-image-10959\" srcset=\"https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/05\/Infographic_V2.jpg-606x1024.jpeg 606w, https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/05\/Infographic_V2.jpg-248x420.jpeg 248w, https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/05\/Infographic_V2.jpg-768x1298.jpeg 768w, https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/05\/Infographic_V2.jpg-908x1536.jpeg 908w, https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/05\/Infographic_V2.jpg-213x360.jpeg 213w, https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/05\/Infographic_V2.jpg.jpeg 1080w\" sizes=\"(max-width: 606px) 100vw, 606px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Qu\u00e9 selecci\u00f3n prefieren los chilenos en el Mundial 2026<\/strong><\/h2>\n\n\n\n<p>De los 1.034 encuestados, la mayor\u00eda asegura que seguir\u00e1 el certamen con la misma intensidad. Cambia el equipo, pero no la emoci\u00f3n.<\/p>\n\n\n\n<p><strong>Ranking de selecciones favoritas en Chile:<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Portugal \u2013 28,6%<\/li>\n\n\n\n<li>Brasil \u2013 20,2%<\/li>\n\n\n\n<li>Espa\u00f1a \u2013 12,7%<\/li>\n\n\n\n<li>Francia \u2013 9,2%<\/li>\n\n\n\n<li>Argentina \u2013 9,1%<\/li>\n<\/ol>\n\n\n\n<p>El dato m\u00e1s relevante: el vigente campe\u00f3n, Argentina, queda fuera del top 3. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Portugal es el nuevo refugio de los hinchas<\/strong> <\/h2>\n\n\n\n<p>El liderazgo de Portugal no es casual. Se convierte en el principal \u201cequipo sustituto\u201d para los chilenos en este Mundial.<\/p>\n\n\n\n<p><strong>Claves del apoyo a Portugal:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lidera especialmente entre hombres (33,8%)<\/li>\n\n\n\n<li>En mujeres, Brasil domina (25,7%), seguido por Portugal (15,2%)<\/li>\n\n\n\n<li>Es la selecci\u00f3n favorita en todos los segmentos menores de 45 a\u00f1os<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"696\" src=\"https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/05\/sdlptHu96f92ls-nh-1024x696.jpg\" alt=\"\" class=\"wp-image-10940\" srcset=\"https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/05\/sdlptHu96f92ls-nh-1024x696.jpg 1024w, https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/05\/sdlptHu96f92ls-nh-420x285.jpg 420w, https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/05\/sdlptHu96f92ls-nh-768x522.jpg 768w, https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/05\/sdlptHu96f92ls-nh-1536x1044.jpg 1536w, https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/05\/sdlptHu96f92ls-nh-2048x1392.jpg 2048w, https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/05\/sdlptHu96f92ls-nh-530x360.jpg 530w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cristiano Ronaldo, el eterno rival de Messi, es el favorito de los chilenos con 40,9% para levantar la Copa del Mundo. (Foto: CARL DE SOUZA \/ AFP)<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Portugal y Cristiano Ronaldo, los grandes protagonistas<\/strong><\/h2>\n\n\n\n<p>Si el respaldo a Portugal tiene una explicaci\u00f3n, gran parte de ella pasa por su capit\u00e1n Cristiano Ronaldo, quien jugar\u00e1 su sexto Mundial: 2006, 2010, 2014, 2018,  2022 y 2026. Adem\u00e1s, CR7 es el \u00fanico jugador en haber marcado en cinco ediciones diferentes. En total, son 22 partidos y ocho goles.<\/p>\n\n\n\n<p>Jugadores que los chilenos quieren ver campeones:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Cristiano Ronaldo \u2013 40,9%<\/li>\n\n\n\n<li>Lionel Messi \u2013 12%<\/li>\n\n\n\n<li>Neymar \u2013 11,2%<\/li>\n\n\n\n<li>Lamine Yamal \u2013 10,7%<\/li>\n\n\n\n<li>Mbapp\u00e9 \u2013 8,5%<\/li>\n<\/ol>\n\n\n\n<p>Cristiano no solo lidera, sino que:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>tiene m\u00e1s apoyo que su propia selecci\u00f3n<\/li>\n\n\n\n<li>domina especialmente entre j\u00f3venes<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/05\/sdlx-eVqadlvUA-nh-1024x683.jpg\" alt=\"\" class=\"wp-image-10944\" srcset=\"https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/05\/sdlx-eVqadlvUA-nh-1024x683.jpg 1024w, https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/05\/sdlx-eVqadlvUA-nh-420x280.jpg 420w, https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/05\/sdlx-eVqadlvUA-nh-768x512.jpg 768w, https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/05\/sdlx-eVqadlvUA-nh-1536x1024.jpg 1536w, https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/05\/sdlx-eVqadlvUA-nh-2048x1365.jpg 2048w, https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/05\/sdlx-eVqadlvUA-nh-540x360.jpg 540w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Lionel Messi tiene el 12% de preferencia de los hinchas chilenos para volver a coronarse en el Mundial. (Foto: Anne-Christine POUJOULAT \/ AFP)<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Argentina, la selecci\u00f3n que genera m\u00e1s dudas en Chile<\/strong><\/h2>\n\n\n\n<p>Si hay un consenso claro en el estudio, es este: Argentina es la principal candidata a decepcionar.<\/p>\n\n\n\n<p>Ranking de selecciones que generan m\u00e1s dudas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Argentina \u2013 32,6%<\/li>\n\n\n\n<li>Brasil \u2013 14,8%<\/li>\n\n\n\n<li>Inglaterra \u2013 14,2%<\/li>\n\n\n\n<li>Uruguay \u2013 13,9%<\/li>\n\n\n\n<li>Espa\u00f1a \u2013 10,1%<\/li>\n<\/ul>\n\n\n\n<p>Esto genera una paradoja interesante:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Argentina est\u00e1 en el top 5 de favoritas<\/li>\n\n\n\n<li>pero lidera como posible decepci\u00f3n<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Claves del Mundial 2026 en Chile seg\u00fan el estudio de Betsson<\/strong><\/h2>\n\n\n\n<p>Portugal aparece como la selecci\u00f3n con mejor imagen entre los hinchas chilenos rumbo al Mundial 2026, seg\u00fan la muestra realizada a m\u00e1s de mil personas. El equipo luso figura entre los principales candidatos al t\u00edtulo y apenas es mencionado entre las posibles decepciones, reflejando la confianza que genera en la previa del torneo.<\/p>\n\n\n\n<p>Argentina, en cambio, es la selecci\u00f3n que m\u00e1s divide opiniones. Aunque se mantiene entre las favoritas para defender el t\u00edtulo conseguido en Qatar 2022, tambi\u00e9n lidera el listado de equipos que podr\u00edan decepcionar. En el plano individual, Cristiano Ronaldo sobresale como la figura m\u00e1s admirada, con muchos aficionados ilusionados con verlo campe\u00f3n y goleador con Portugal en el tramo final de su carrera.<\/p>\n\n\n\n<p>Para conocer m\u00e1s detalles de la encuesta, ingresa a <a href=\"https:\/\/www.betsson1001.com\/cl\/blog\/futbol\/mundial\/fandom-chileno-mundial-2026\/\" data-type=\"link\" data-id=\"https:\/\/www.betsson1001.com\/cl\/blog\/futbol\/mundial\/fandom-chileno-mundial-2026\/\" target=\"_blank\" rel=\"noopener\">betsson.com<\/a>. <\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una encuesta de Betsson revel\u00f3 que, pese a la ausencia de la Roja, los chilenos vivir\u00e1n con intensidad el Mundial 2026: Portugal aparece como la selecci\u00f3n favorita, Cristiano Ronaldo es el jugador m\u00e1s apoyado y Argentina lidera el ranking de posibles decepciones.<\/p>\n","protected":false},"author":3,"featured_media":10941,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"_acf_changed":true,"footnotes":""},"categories":[1798],"tags":[73,181,1755,3269,3268,2425,311,499,431,3267],"label":[],"country":[1475],"class_list":["post-10931","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundial","tag-chile","tag-copa-del-mundo","tag-copa-mundial-2026","tag-crisitano-ronaldo","tag-encuesta","tag-fifa-2026","tag-la-roja","tag-messi","tag-mundial-2026","tag-seleccion-chile","country-chile"],"acf":[],"_links":{"self":[{"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/posts\/10931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/comments?post=10931"}],"version-history":[{"count":0,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/posts\/10931\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/media\/10941"}],"wp:attachment":[{"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/media?parent=10931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/categories?post=10931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/tags?post=10931"},{"taxonomy":"label","embeddable":true,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/label?post=10931"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/country?post=10931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}