{"id":10947,"date":"2026-05-12T16:16:24","date_gmt":"2026-05-12T19:16:24","guid":{"rendered":"https:\/\/betsson.sport\/es\/?p=10947"},"modified":"2026-05-12T16:18:25","modified_gmt":"2026-05-12T19:18:25","slug":"otra-vez-cain-fara-el-defensor-fue-clave-para-el-empate-de-universitario","status":"publish","type":"post","link":"https:\/\/betsson.sport\/es\/noticias\/futbol\/liga-1-peru\/otra-vez-cain-fara-el-defensor-fue-clave-para-el-empate-de-universitario\/","title":{"rendered":"Otra vez Ca\u00edn Fara: el defensor fue clave para el empate de Universitario"},"content":{"rendered":"\n<p>Fue un partido muy discreto, con emociones solo en los minutos de descuento del complemento. Sport Boys y Universitario de Deportes no se hicieron da\u00f1o en el Miguel Grau del Callao y terminaron igualando sin goles por la fecha 14 del Torneo Apertura.<\/p>\n\n\n\n<p>Fue un partido con pocas luces para ambos equipos, sobre todo para los visitantes, que al minuto de juego se quedaron con uno menos por la expulsi\u00f3n de Jos\u00e9 Carabal\u00ed. El ecuatoriano trab\u00f3 a Luis Urruti cerca del \u00e1rea. El \u00e1rbitro consider\u00f3 que cort\u00f3 una ocasi\u00f3n manifiesta de gol y que deb\u00eda dejar la cancha apenas iniciado el compromiso.<\/p>\n\n\n\n<p>A partir de ese momento, los dirigidos por Jorge Araujo pr\u00e1cticamente renunciaron a atacar y se dedicaron a tratar de mantener el cero en arco propio para poder puntuar. Boys lo intent\u00f3, pero sin claridad, en gran parte por falta de capacidad para generar juego y porque, cuando la tuvo, se encontr\u00f3 con la muralla crema. Ca\u00edn Fara volvi\u00f3 a estar impecable atr\u00e1s y fue clave para que los de Ate rescataran un punto en su visita a la Provincia Constitucional.<\/p>\n\n\n\n<p>Fara demostr\u00f3 que puede funcionar en l\u00ednea de tres o de cuatro defensores y seguir garantiz\u00e1ndoles a los cremas solvencia y seguridad atr\u00e1s. Complet\u00f3 su decimotercer partido como titular de catorce posibles, en los que no solo ha aportado su cuota de solidez defensiva, sino que tambi\u00e9n ha sumado dos anotaciones.<\/p>\n\n\n\n<p>El de ayer debe haber sido el pen\u00faltimo partido de Jorge Araujo al mando del primer equipo, ya que se confirm\u00f3 que a mitad de semana arribar\u00e1 a nuestro pa\u00eds H\u00e9ctor C\u00faper para asumir el cargo. No se sabe si mantendr\u00e1 el 3-5-2 como sistema base o si lo cambiar\u00e1. Lo que es seguro es que, con este nivel, el argentino que lleg\u00f3 este a\u00f1o a nuestro pa\u00eds seguir\u00e1 siendo uno de los jugadores inamovibles en la formaci\u00f3n de la \u2018U\u2019.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Universitario de Deportes igual\u00f3 a cero ante Sport Boys en El Callao. Ca\u00edn Fara, lo m\u00e1s rescatable de los cremas. <\/p>\n","protected":false},"author":17,"featured_media":10948,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":true,"footnotes":""},"categories":[1780],"tags":[1601,206,3264,224,223,110,204],"label":[],"country":[1479],"class_list":["post-10947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-liga-1-peru","tag-cain-fara","tag-futbol-peruano","tag-hector-cuper-2","tag-liga-1-peru","tag-peru-2","tag-universitario","tag-universitario-de-deportes","country-peru"],"acf":[],"_links":{"self":[{"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/posts\/10947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/comments?post=10947"}],"version-history":[{"count":0,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/posts\/10947\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/media\/10948"}],"wp:attachment":[{"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/media?parent=10947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/categories?post=10947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/tags?post=10947"},{"taxonomy":"label","embeddable":true,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/label?post=10947"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/country?post=10947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}