{"id":14288,"date":"2026-07-15T11:59:26","date_gmt":"2026-07-15T14:59:26","guid":{"rendered":"https:\/\/betsson.sport\/es\/?p=14288"},"modified":"2026-07-15T11:59:28","modified_gmt":"2026-07-15T14:59:28","slug":"orbelin-pineda-en-la-mira-de-monterrey-el-mediocampista-analiza-un-posible-regreso-a-la-liga-mx","status":"publish","type":"post","link":"https:\/\/betsson.sport\/es\/noticias\/futbol\/mercado-de-fichajes\/orbelin-pineda-en-la-mira-de-monterrey-el-mediocampista-analiza-un-posible-regreso-a-la-liga-mx\/","title":{"rendered":"Orbel\u00edn Pineda, en la mira de Monterrey: el mediocampista analiza un posible regreso a la Liga MX"},"content":{"rendered":"\n<p>A pocos d\u00edas del debut de Rayados de Monterrey en la Jornada 1 del torneo Apertura 2026 de la Liga MX, el club vive semanas de mucho movimiento y expectativa. Despu\u00e9s de un semestre que dej\u00f3 una profunda sensaci\u00f3n de frustraci\u00f3n entre la afici\u00f3n, tras quedarse fuera de la Liguilla y no cumplir con las expectativas, la directiva trabaja contrarreloj para fortalecer un plantel que necesita recuperar la confianza y volver a competir por los primeros lugares.<\/p>\n\n\n\n<p>En ese contexto, el nombre de Orbel\u00edn Pineda ha cobrado fuerza como una de las principales opciones para reforzar al equipo regiomontano. Luego de representar a la Selecci\u00f3n Mexicana en el Mundial 2026, el mediocampista disfruta de un periodo de descanso mientras su futuro contin\u00faa siendo tema de conversaci\u00f3n. Aunque mantiene contrato con el AEK de Atenas, distintos reportes se\u00f1alan que existe un inter\u00e9s serio por parte de Rayados para intentar concretar su regreso a la Liga MX.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/07\/sdlUVkJsbBQ21c-nh-1024x683.jpg\" alt=\"\" class=\"wp-image-14290\" srcset=\"https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/07\/sdlUVkJsbBQ21c-nh-1024x683.jpg 1024w, https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/07\/sdlUVkJsbBQ21c-nh-420x280.jpg 420w, https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/07\/sdlUVkJsbBQ21c-nh-768x512.jpg 768w, https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/07\/sdlUVkJsbBQ21c-nh-1536x1024.jpg 1536w, https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/07\/sdlUVkJsbBQ21c-nh-2048x1365.jpg 2048w, https:\/\/betsson.sport\/es\/wp-content\/uploads\/2026\/07\/sdlUVkJsbBQ21c-nh-540x360.jpg 540w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Giorgos Arapekos\/NurPhoto\/TT<\/figcaption><\/figure>\n\n\n\n<p>Orbel\u00edn conoce bien el futbol mexicano. Antes de cumplir el sue\u00f1o europeo, defendi\u00f3 los colores de Quer\u00e9taro, Chivas y Cruz Azul, dejando huella por su calidad, entrega y capacidad para marcar diferencia en momentos importantes. Su paso por Europa comenz\u00f3 en 2022 con el Celta de Vigo y, posteriormente, encontr\u00f3 continuidad en el AEK de Atenas, donde logr\u00f3 consolidarse.<\/p>\n\n\n\n<p>Por ahora, las negociaciones entre ambos clubes contin\u00faan y todav\u00eda no existe un acuerdo definitivo. Sin embargo, diversas versiones apuntan a que el futbolista ver\u00eda con buenos ojos la posibilidad de vestir la camiseta de Rayados. Mientras tanto, la afici\u00f3n permanece atenta, con la esperanza de que la directiva pueda concretar un refuerzo que ilusione de nuevo y ayude a cambiar el rumbo del equipo en este nuevo torneo. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pocos d\u00edas del debut de Rayados de Monterrey en la Jornada 1 del torneo Apertura 2026 de la Liga MX, el club vive semanas de mucho movimiento y expectativa. Despu\u00e9s de un semestre que dej\u00f3 una profunda sensaci\u00f3n de frustraci\u00f3n entre la afici\u00f3n, tras quedarse fuera de la Liguilla y no cumplir con las [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":14289,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[3961,66,118,3960,3962,437],"label":[],"country":[1477],"class_list":["post-14288","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado-de-fichajes","tag-aek-atenas","tag-liga-mx","tag-monterrey","tag-orbelin-pineda","tag-rayados-de-monterrey","tag-seleccion-mexicana","country-mexico"],"acf":[],"_links":{"self":[{"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/posts\/14288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/comments?post=14288"}],"version-history":[{"count":0,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/posts\/14288\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/media\/14289"}],"wp:attachment":[{"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/media?parent=14288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/categories?post=14288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/tags?post=14288"},{"taxonomy":"label","embeddable":true,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/label?post=14288"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/betsson.sport\/es\/wp-json\/wp\/v2\/country?post=14288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}